{"id":4831,"date":"2026-05-13T10:43:24","date_gmt":"2026-05-13T08:43:24","guid":{"rendered":"https:\/\/euskalkirolatb.eus\/?post_type=retransmisiones&#038;p=4831"},"modified":"2026-05-13T10:43:24","modified_gmt":"2026-05-13T08:43:24","slug":"euskalkirolatb-magazine-27-05-2026","status":"publish","type":"retransmisiones","link":"https:\/\/euskalkirolatb.eus\/eu\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/","title":{"rendered":"EuskalkirolaTB Magazine 27-05-2026"},"content":{"rendered":"<p style=\"padding-left: 40px;\">No<\/p>\n","protected":false},"featured_media":759,"template":"","meta":{"_acf_changed":false},"deporte":[23],"class_list":["post-4831","retransmisiones","type-retransmisiones","status-publish","has-post-thumbnail","hentry","deporte-euskalkirolatb-magazine","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EuskalkirolaTB Magazine 27-05-2026 - Euskal Kirola Telebista<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuskalkirolaTB Magazine 27-05-2026 - Euskal Kirola Telebista\" \/>\n<meta property=\"og:description\" content=\"No\" \/>\n<meta property=\"og:url\" content=\"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Euskal Kirola Telebista\" \/>\n<meta property=\"og:image\" content=\"https:\/\/euskalkirolatb.eus\/wp-content\/uploads\/2022\/01\/EKMagazine.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/\",\"url\":\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/\",\"name\":\"EuskalkirolaTB Magazine 27-05-2026 - Euskal Kirola Telebista\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/euskalkirolatb.eus\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/EKMagazine.png\",\"datePublished\":\"2026-05-13T08:43:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/euskalkirolatb.eus\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/EKMagazine.png\",\"contentUrl\":\"https:\\\/\\\/euskalkirolatb.eus\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/EKMagazine.png\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/retransmisiones\\\/euskalkirolatb-magazine-27-05-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/euskalkirolatb.eus\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuskalkirolaTB Magazine 27-05-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/euskalkirolatb.eus\\\/#website\",\"url\":\"https:\\\/\\\/euskalkirolatb.eus\\\/\",\"name\":\"Euskal Kirola Telebista\",\"description\":\"Otro sitio realizado con WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/euskalkirolatb.eus\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EuskalkirolaTB Magazine 27-05-2026 - Euskal Kirola Telebista","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/","og_locale":"eu_ES","og_type":"article","og_title":"EuskalkirolaTB Magazine 27-05-2026 - Euskal Kirola Telebista","og_description":"No","og_url":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/","og_site_name":"Euskal Kirola Telebista","og_image":[{"width":1024,"height":576,"url":"https:\/\/euskalkirolatb.eus\/wp-content\/uploads\/2022\/01\/EKMagazine.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/","url":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/","name":"EuskalkirolaTB Magazine 27-05-2026 - Euskal Kirola Telebista","isPartOf":{"@id":"https:\/\/euskalkirolatb.eus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/#primaryimage"},"image":{"@id":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/euskalkirolatb.eus\/wp-content\/uploads\/2022\/01\/EKMagazine.png","datePublished":"2026-05-13T08:43:24+00:00","breadcrumb":{"@id":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/#primaryimage","url":"https:\/\/euskalkirolatb.eus\/wp-content\/uploads\/2022\/01\/EKMagazine.png","contentUrl":"https:\/\/euskalkirolatb.eus\/wp-content\/uploads\/2022\/01\/EKMagazine.png","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/euskalkirolatb.eus\/retransmisiones\/euskalkirolatb-magazine-27-05-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/euskalkirolatb.eus\/eu\/"},{"@type":"ListItem","position":2,"name":"EuskalkirolaTB Magazine 27-05-2026"}]},{"@type":"WebSite","@id":"https:\/\/euskalkirolatb.eus\/#website","url":"https:\/\/euskalkirolatb.eus\/","name":"Euskal Kirola Telebista","description":"Otro sitio realizado con WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/euskalkirolatb.eus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"}]}},"_links":{"self":[{"href":"https:\/\/euskalkirolatb.eus\/eu\/wp-json\/wp\/v2\/retransmisiones\/4831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euskalkirolatb.eus\/eu\/wp-json\/wp\/v2\/retransmisiones"}],"about":[{"href":"https:\/\/euskalkirolatb.eus\/eu\/wp-json\/wp\/v2\/types\/retransmisiones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euskalkirolatb.eus\/eu\/wp-json\/wp\/v2\/media\/759"}],"wp:attachment":[{"href":"https:\/\/euskalkirolatb.eus\/eu\/wp-json\/wp\/v2\/media?parent=4831"}],"wp:term":[{"taxonomy":"deporte","embeddable":true,"href":"https:\/\/euskalkirolatb.eus\/eu\/wp-json\/wp\/v2\/deporte?post=4831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}